{"id":22562,"date":"2024-10-08T09:00:23","date_gmt":"2024-10-08T07:00:23","guid":{"rendered":"https:\/\/www.generationsanstabac.org\/?post_type=actualites&#038;p=22562"},"modified":"2024-10-08T10:55:24","modified_gmt":"2024-10-08T08:55:24","slug":"les-guerres-et-les-conflits-terrains-prosperes-pour-lindustrie-du-tabac","status":"publish","type":"actualites","link":"https:\/\/www.generationsanstabac.org\/fr\/actualites\/les-guerres-et-les-conflits-terrains-prosperes-pour-lindustrie-du-tabac\/","title":{"rendered":"Les guerres et les conflits, terrains prosp\u00e8res pour l\u2019industrie du tabac"},"content":{"rendered":"<p style=\"text-align: justify\"><em>Un billet d\u2019opinion<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a> publi\u00e9 dans le blog du British Medical Journal montre comment l\u2019industrie du tabac prosp\u00e8re au milieu des guerres et des conflits. Plus r\u00e9cemment, l&rsquo;industrie du tabac a offert des cigarettes gratuites aux recrues ukrainiennes form\u00e9es au Royaume-Uni et a maintenu ses activit\u00e9s en Russie alors que les entreprises \u00e9taient cens\u00e9es quitter ce territoire. <\/em><\/p>\n<p style=\"text-align: justify\">La mani\u00e8re dont les fabricants de tabac ont tir\u00e9 profit des guerres depuis la Premi\u00e8re Guerre mondiale est bien document\u00e9e. Les fabricants de tabac ont cibl\u00e9 les troupes avec des cigarettes gratuites, de la publicit\u00e9 directe, des articles de marque et des \u00e9v\u00e9nements de \u00ab\u00a0bienvenue \u00e0 la maison\u00bb. Un ph\u00e9nom\u00e8ne qui se poursuit encore aujourd\u2019hui et l\u2019implication des cigarettiers dans les diff\u00e9rents conflits rev\u00eats diverses facettes (Distribution de produits de tabac et de la nicotine aux soldats, promotion des produits du tabac dans des pays fragilis\u00e9s par des conflits, implication dans le commerce illicite, etc.)<\/p>\n<h2 style=\"text-align: justify\"><strong>La guerre en Ukraine, une situation profitable pour les cigarettiers<\/strong><\/h2>\n<p style=\"text-align: justify\">Apr\u00e8s l&rsquo;invasion de l&rsquo;Ukraine par la Russie en mars 2022, d\u00e9clenchant des sanctions occidentales, de nombreuses grandes soci\u00e9t\u00e9s transnationales, y compris des compagnies de tabac, se sont engag\u00e9es \u00e0 se retirer de la Russie. Ainsi, les fabricants Philip Morris International (PMI), British American Tobacco (BAT) et Japan Tobacco International (JTI) ont annonc\u00e9 qu&rsquo;ils quittaient le march\u00e9 russe. Toutefois, les actes n\u2019ont pas suivi ces paroles, puisque PMI et JTI restent profond\u00e9ment ancr\u00e9s sur le march\u00e9 russe.<\/p>\n<p style=\"text-align: justify\">Avec une pr\u00e9valence tabagique de 27% en Russie, le pays est un march\u00e9 lucratif pour les cigarettiers. En 2021, la Russie repr\u00e9sentait environ 10 % des ventes de produits du tabac de Philip Morris et 6 % de son chiffre d&rsquo;affaires net d\u2019un montant de 31 milliards de dollars.\u00a0 De m\u00eame, Japan Tobacco, qui tire 20 % de ses b\u00e9n\u00e9fices globaux dans le tabac du march\u00e9 russe, a d\u00e9cid\u00e9, en mai 2024, de poursuivre ses activit\u00e9s en Russie pour satisfaire les investisseurs, malgr\u00e9 l&rsquo;annonce pr\u00e9alable de son retrait en 2022. JTI emploie plus de 4 000 personnes et poss\u00e8de quatre usines en Russie, ce qui en fait l&rsquo;une des plus grandes entreprises \u00e9trang\u00e8res encore pr\u00e9sentes dans le pays. \u00a0En 2022, ces entreprises ont respectivement engrang\u00e9 7,9 milliards US$ et 7,4 milliards US$ en profit et elles ont vers\u00e9 \u00e0 la Russie des centaines de millions de US$ d\u2019imp\u00f4t sur les b\u00e9n\u00e9fices, 206 millions pour Philip Morris et 193 millions US$ pour Japan Tobacco<\/p>\n<p style=\"text-align: justify\">En Ukraine, PMI contr\u00f4le environ un quart (24 %) du march\u00e9 des cigarettes. Apr\u00e8s avoir suspendu temporairement sa production en 2022, PMI a continu\u00e9 \u00e0 fournir ses cigarettes \u00e0 l&rsquo;Ukraine \u00e0 partir de huit usines situ\u00e9es \u00e0 l&rsquo;ext\u00e9rieur du pays et en s&rsquo;associant avec le cigarettier Imperial Brands qui op\u00e8re toujours en Ukraine. Philip Morris a r\u00e9tabli ses activit\u00e9s en l&rsquo;espace d&rsquo;une semaine apr\u00e8s le d\u00e9but de la guerre et repris ses op\u00e9rations avec les d\u00e9taillants.<\/p>\n<p style=\"text-align: justify\">Un article du Telegraph<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> avait r\u00e9v\u00e9l\u00e9 d\u00e9but 2024 un accord pass\u00e9 entre le Royaume-Uni et l\u2019Ukraine permettant d\u2019offrir des cigarettes, sachets de nicotine et cigarettes \u00e9lectroniques aux soldats ukrainiens venus s\u2019entra\u00eener outre-Manche. Ces produits ont \u00e9t\u00e9 offerts par l\u2019une des compagnies internationales de tabac, rest\u00e9e anonyme, et distribu\u00e9es aux soldats dans le cadre de leur ration.\u00a0Comme le souligne le Telegraph, une source proche du dossier aurait affirm\u00e9 que le tabagisme \u00ab<em> constitue une menace plus faible pour ces courageux soldats que de lutter contre l\u2019invasion ill\u00e9gale de leur pays par Poutine \u00bb.<\/em><\/p>\n<h2 style=\"text-align: justify\"><strong>L\u2019industrie du tabac profite de l\u2019instabilit\u00e9 de certaines r\u00e9gions africaines<\/strong><\/h2>\n<p style=\"text-align: justify\">En Afrique, le Soudan est en proie \u00e0 une guerre civile depuis avril 2023, entrainant une situation humanitaire dramatique : plus de 8 millions de personnes ont fui leur foyer, 25 millions de personnes souffrent de la faim et la moiti\u00e9 de la population du pays est d\u00e9pendante d&rsquo;une aide vitale. Cette crise a affect\u00e9 la fabrication et les ventes de cigarettes de British American Tobacco. Pour rem\u00e9dier \u00e0 cette situation, BAT a fait pression sur le gouvernement pour qu&rsquo;il modifie la r\u00e9glementation afin de pouvoir fabriquer des petits paquets de 10 cigarettes et les exporter au Soudan et dans d&rsquo;autres march\u00e9s o\u00f9 ils ne sont pas interdits. Ces petits paquets de cigarettes, connus sous le nom de \u00ab\u00a0kiddie packs\u00a0\u00bb, ou \u00ab paquets enfant \u00bb facilitent l&rsquo;achat de cigarettes par les plus jeunes et les populations les plus d\u00e9munies. Leur prix est en effet moindre et ce proc\u00e9d\u00e9 rend les cigarettes plus abordables et donc plus susceptibles d\u2019\u00eatre achet\u00e9es<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>. BAT esp\u00e8re ainsi que l\u2019autorisation accord\u00e9e pour une exportation au Soudan sera suivie d\u2019autres autorisations pour d&rsquo;autres pays africains.<\/p>\n<p style=\"text-align: justify\">En 2021, une enqu\u00eate de l\u2019Organized Crime and Corruption Reporting Project (OCCRP) avait d\u00e9voil\u00e9 comment l\u2019industrie du tabac alimente massivement et d\u00e9lib\u00e9r\u00e9ment la contrebande de tabac en Afrique de l\u2019Ouest, alors m\u00eame que cette derni\u00e8re finance la militarisation de la criminalit\u00e9 organis\u00e9e, les milices ethniques et les organisations terroristes islamistes<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>. L\u2019enqu\u00eate r\u00e9v\u00e8lait par ailleurs que le repr\u00e9sentant de Philip Morris au Burkina-Faso, Apollinaire Compaor\u00e9, fich\u00e9 comme contrebandier par l\u2019ONU elle-m\u00eame, \u00e9tait \u00e0 la t\u00eate d\u2019un trafic annuel de milliards de cigarettes \u00e0 destination de l\u2019Afrique du Nord (Libye, Alg\u00e9rie).<\/p>\n<h2 style=\"text-align: justify\"><strong>Au Moyen-Orient, les pays en guerre continuent d\u2019exporter et importer massivement des cigarettes<\/strong><\/h2>\n<p style=\"text-align: justify\">Le Y\u00e9men, en conflit depuis neuf ans, est confront\u00e9 \u00e0 l\u2019une plus graves crises humanitaires au monde. Pourtant, en 2019, le Y\u00e9men a import\u00e9 pour 15 957,65K$ de cigarettes (3 361 440Kg), principalement des \u00c9mirats arabes unis. L&rsquo;ancien ambassadeur britannique au Y\u00e9men a assist\u00e9 fin 2019 \u00e0 l&rsquo;ouverture d&rsquo;une usine de fabrication de tabac appartenant conjointement au gouvernement y\u00e9m\u00e9nite, au fabricant de cigarettes Kamaran et \u00e0 BAT, comme l&rsquo;a r\u00e9v\u00e9l\u00e9 le groupe de recherche sur la lutte contre le tabagisme de l&rsquo;Universit\u00e9 de Bath. L&rsquo;ambassadeur avait d\u00e9clar\u00e9 que l\u2019ouverture de cette usine \u00e9tait un investissement pr\u00e9cieux pour BAT et l&rsquo;\u00e9conomie y\u00e9m\u00e9nite. Il a, par la suite, admis qu&rsquo;il s&rsquo;agissait d&rsquo;une erreur et qu&rsquo;il n&rsquo;\u00e9tait pas dans ses intentions de promouvoir le fabricant de tabac.<\/p>\n<p style=\"text-align: justify\">En Syrie, la guerre civile depuis 2011, a entra\u00een\u00e9 le d\u00e9placement forc\u00e9 de plus de 12 millions de personnes dans toute la r\u00e9gion. Pourtant, le pays reste un exportateur de tabac. En 2023, la base de donn\u00e9es de la Banque mondiale a enregistr\u00e9 des exportations syriennes de cigares ou de cigarettes vers les principaux importateurs que sont le Liban (771,68 K$, 54 174 kg), la Jordanie (44,37 K$, 3 115 kg) et le Qatar (31,80 K$, 2 233 kg).<\/p>\n<p style=\"text-align: justify\">Les auteurs concluent que certains partisans de l&rsquo;industrie du tabac pourraient faire valoir que la poursuite des activit\u00e9s habituelles est source d&#8217;emplois et de revenus. En r\u00e9alit\u00e9, la poursuite du commerce des produits de consommation les plus meurtriers au monde prolonge et exacerbe les difficult\u00e9s de la guerre, et conduit \u00e0 une augmentation du fardeau de la pauvret\u00e9, de la morbidit\u00e9 et de la mortalit\u00e9 actuelle et \u00e0 venir. Ils ajoutent qu&rsquo;il est important de d\u00e9noncer toutes les pratiques contraires \u00e0 l&rsquo;\u00e9thique de la part de l&rsquo;industrie du tabac.<\/p>\n<p style=\"text-align: justify\"><strong><a href=\"https:\/\/www.generationsanstabac.org\/\">\u00a9G\u00e9n\u00e9ration Sans Tabac<\/a><\/strong><\/p>\n<p style=\"text-align: right\"><b><i>AE<\/i><\/b><\/p>\n<hr \/>\n<p style=\"text-align: justify\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Mary Assunta, Dmytro Kupyra, <a href=\"https:\/\/blogs.bmj.com\/tc\/2024\/10\/02\/no-ceasefire-for-tobacco-how-the-industry-thrives-amid-war-and-conflict\/\">No Ceasefire for Tobacco: How the Industry Thrives Amid War and Conflict<\/a>, BMJ Blog, publi\u00e9 le 2 octobre 2024, consult\u00e9 le 4 octobre 2024<\/p>\n<p style=\"text-align: justify\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> G\u00e9n\u00e9ration sans tabac, <a href=\"https:\/\/www.generationsanstabac.org\/fr\/actualites\/royaume-uni-offre-cigarettes-soldats-ukrainiens\/\">Le Royaume-Uni distribue des cigarettes gratuites aux soldats ukrainiens<\/a>, publi\u00e9 le 25 avril 2024, consult\u00e9 le 4 octobre 2024<\/p>\n<p style=\"text-align: justify\"><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> G\u00e9n\u00e9ration sans tabac, <a href=\"https:\/\/www.generationsanstabac.org\/fr\/actualites\/british-american-tobacco-fait-pression-sur-le-pakistan-pour-pouvoir-exporter-des-paquets-enfant-de-cigarettes-au-soudan\/\">British American Tobacco fait pression sur le Pakistan pour pouvoir exporter des \u00ab paquets-enfant \u00bb de cigarettes au Soudan<\/a>, publi\u00e9 le 12 juillet 2024, consult\u00e9 le 4 octobre 2024<\/p>\n<p style=\"text-align: justify\"><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> G\u00e9n\u00e9ration sans tabac, <a href=\"https:\/\/www.generationsanstabac.org\/fr\/actualites\/afrique-contrebande-philip-morris-terrorisme\/\">Afrique : la contrebande de Philip Morris finance les organisations terroristes<\/a>, publi\u00e9 le 3 mars 2021, consult\u00e9 le 4 octobre 2024<\/p>\n<p><span style=\"color: #999999\"><strong><a style=\"color: #999999\" href=\"http:\/\/www.cnct.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comit\u00e9 national contre le tabagisme |<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un billet d\u2019opinion publi\u00e9 dans le blog du British Medical Journal montre comment l\u2019industrie du tabac prosp\u00e8re au milieu des guerres et des conflits. Plus r\u00e9cemment, l&rsquo;industrie du tabac a offert des cigarettes gratuites aux recrues ukrainiennes form\u00e9es au Royaume-Uni et a maintenu ses activit\u00e9s en Russie alors que les entreprises \u00e9taient cens\u00e9es quitter ce territoire.<\/p>\n","protected":false},"featured_media":22568,"template":"","tags":[],"thematique":[499,538],"class_list":["post-22562","actualites","type-actualites","status-publish","has-post-thumbnail","hentry","thematique-lobby","thematique-marches-paralleles"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/actualites\/22562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/actualites"}],"about":[{"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/types\/actualites"}],"version-history":[{"count":0,"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/actualites\/22562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/media\/22568"}],"wp:attachment":[{"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/media?parent=22562"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/tags?post=22562"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/fr\/wp-json\/wp\/v2\/thematique?post=22562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}