{"id":26815,"date":"2026-05-13T07:00:48","date_gmt":"2026-05-13T05:00:48","guid":{"rendered":"https:\/\/www.generationsanstabac.org\/?post_type=actualites&#038;p=26815"},"modified":"2026-05-11T14:44:04","modified_gmt":"2026-05-11T12:44:04","slug":"argentine-le-gouvernement-met-fin-a-linterdiction-du-tabac-chauffe-des-sachets-de-nicotine-et-produits-du-vapotage","status":"publish","type":"actualites","link":"https:\/\/www.generationsanstabac.org\/en\/actualites\/argentine-le-gouvernement-met-fin-a-linterdiction-du-tabac-chauffe-des-sachets-de-nicotine-et-produits-du-vapotage\/","title":{"rendered":"Argentina: The government ends the ban on heated tobacco, nicotine pouches, and vaping products."},"content":{"rendered":"<p style=\"text-align: justify\"><em>Le gouvernement argentin a adopt\u00e9 un nouveau cadre r\u00e9glementaire autorisant la commercialisation des cigarettes \u00e9lectroniques, des produits du tabac chauff\u00e9 et des sachets de nicotine, revenant ainsi sur plusieurs ann\u00e9es d\u2019interdiction de ces produits dans le pays. Publi\u00e9e d\u00e9but mai 2026, la <\/em><a href=\"https:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/341494\/20260504\"><em>r\u00e9solution 549\/2026<\/em><\/a><em> cr\u00e9e un r\u00e9gime d\u2019autorisation, d\u2019enregistrement et de contr\u00f4le applicable aux nouveaux produits nicotiniques. Les autorit\u00e9s argentines pr\u00e9sentent cette \u00e9volution comme une r\u00e9ponse \u00e0 l\u2019\u00e9chec de la prohibition, estimant que ces produits continuaient \u00e0 circuler massivement via des circuits informels sans contr\u00f4le sanitaire ni fiscal<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a>.<\/em><\/p>\n<p style=\"text-align: justify\">Le gouvernement affirme vouloir mieux encadrer un march\u00e9 d\u00e9j\u00e0 largement implant\u00e9, notamment chez les adolescents. Toutefois, cette d\u00e9cision suscite une vive opposition des organisations de sant\u00e9 publique, qui d\u00e9noncent un \u00ab grave recul \u00bb pour la lutte contre la d\u00e9pendance \u00e0 la nicotine et la protection des jeunes. Plusieurs soci\u00e9t\u00e9s savantes et associations m\u00e9dicales argentines alertent notamment sur le risque de normalisation des usages nicotiniques et sur l\u2019ouverture d\u2019un nouveau march\u00e9 pour l\u2019industrie du tabac et de la nicotine, dans un contexte de forte progression du vapotage chez les adolescents.<\/p>\n<h2 style=\"text-align: justify\"><strong>Une lev\u00e9e des interdictions malgr\u00e9 une hausse pr\u00e9occupante du vapotage chez les jeunes<\/strong><\/h2>\n<p style=\"text-align: justify\">La r\u00e9forme abroge les pr\u00e9c\u00e9dentes mesures restrictives adopt\u00e9es par les autorit\u00e9s sanitaires argentines. La r\u00e9solution 565\/2023, qui interdisait les produits du tabac chauff\u00e9, est supprim\u00e9e, tandis que l\u2019<a href=\"https:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/341513\/20260504\">ANMAT<\/a> revient \u00e9galement sur sa disposition historique de 2011 interdisant l\u2019importation, la commercialisation et la publicit\u00e9 des cigarettes \u00e9lectroniques en Argentine. Le nouveau dispositif cr\u00e9e d\u00e9sormais un r\u00e9gime d\u2019autorisation et de contr\u00f4le des produits du tabac et de la nicotine. Les fabricants et importateurs devront enregistrer les produits, d\u00e9clarer leur composition et respecter certaines exigences r\u00e9glementaires. Le texte pr\u00e9voit notamment des avertissements sanitaires obligatoires, des limitations relatives aux \u00e9l\u00e9ments de design susceptibles d\u2019attirer les mineurs ainsi que certaines restrictions sur les ar\u00f4mes autoris\u00e9s. Seuls les ar\u00f4mes tabac et menthol restent autoris\u00e9s pour les sachets de nicotine, tandis que les cigarettes \u00e9lectroniques et produits chauff\u00e9s devront \u00eatre limit\u00e9s aux saveurs tabac.<\/p>\n<p style=\"text-align: justify\">Le gouvernement soutient que cette mesure vise \u00e0 reprendre le contr\u00f4le d\u2019un march\u00e9 d\u00e9j\u00e0 largement existant et \u00e0 lutter contre le commerce ill\u00e9gal. Les autorit\u00e9s invoquent notamment des donn\u00e9es nationales montrant une progression importante du vapotage chez les adolescents. Selon les chiffres cit\u00e9s dans la r\u00e9solution 549\/2026, la pr\u00e9valence d\u2019usage des cigarettes \u00e9lectroniques atteindrait 35,5 % chez les lyc\u00e9ens au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e.<\/p>\n<p style=\"text-align: justify\">Ce point constitue toutefois l\u2019un des principaux paradoxes d\u00e9nonc\u00e9s par les organisations de sant\u00e9 : alors m\u00eame que les autorit\u00e9s reconnaissent des niveaux de consommation \u00ab alarmants \u00bb chez les jeunes, elles choisissent d\u2019ouvrir l\u00e9galement le march\u00e9 de ces produits et d\u2019en banaliser la consommation.<\/p>\n<h2 style=\"text-align: justify\"><strong>Les organisations de sant\u00e9 d\u00e9noncent un \u00ab grave recul \u00bb pour la sant\u00e9 publique<\/strong><\/h2>\n<p style=\"text-align: justify\">\u00c0 la suite de l\u2019annonce gouvernementale, plusieurs organisations m\u00e9dicales et de sant\u00e9 publique argentines ont publi\u00e9 un communiqu\u00e9 commun demandant la suspension imm\u00e9diate de la r\u00e9forme. Parmi les signataires figurent notamment l\u2019Union Antitabac Argentine (UATA), l\u2019Association argentine de tabacologie (AsAT), la Soci\u00e9t\u00e9 argentine de m\u00e9decine (SAM), la F\u00e9d\u00e9ration argentine de cardiologie (FAC) et la Soci\u00e9t\u00e9 argentine de p\u00e9diatrie (SAP).<\/p>\n<p style=\"text-align: justify\">Les organisations d\u00e9noncent une d\u00e9cision qui, selon elles, \u00ab ouvre la porte \u00e0 l\u2019expansion d\u2019un march\u00e9 de produits addictifs \u00bb, promus \u00e0 travers des strat\u00e9gies commerciales reposant sur \u00ab l\u2019innovation technologique, le design attractif, la perception de moindre danger et la captation de nouveaux consommateurs \u00bb. Elles estiment que cette \u00e9volution affaiblit les politiques de pr\u00e9vention et de protection des mineurs face \u00e0 la d\u00e9pendance \u00e0 la nicotine. Les signataires rappellent \u00e9galement que les produits concern\u00e9s ne sont pas sans risque pour la sant\u00e9. Ils soulignent les effets de la nicotine sur le d\u00e9veloppement c\u00e9r\u00e9bral des adolescents, les risques cardiovasculaires, les atteintes respiratoires li\u00e9es aux produits inhal\u00e9s ainsi que les risques d\u2019intoxications accidentelles et de toxicit\u00e9 pendant la grossesse.<\/p>\n<p style=\"text-align: justify\">Le communiqu\u00e9 insiste \u00e9galement sur l\u2019absence d\u2019\u00e9l\u00e9ments scientifiques ind\u00e9pendants permettant de justifier cette \u00e9volution r\u00e9glementaire. Les organisations estiment que les incertitudes persistantes concernant les effets \u00e0 long terme des cigarettes \u00e9lectroniques, des produits chauff\u00e9s et des sachets de nicotine devraient au contraire conduire \u00e0 appliquer le principe de pr\u00e9caution et appliquer de mani\u00e8re effective les dispositions en jusqu\u2019alors en vigueur plut\u00f4t qu\u2019\u00e0 organiser leur commercialisation \u00e0 grande \u00e9chelle.<\/p>\n<h2 style=\"text-align: justify\"><strong>Une ouverture du march\u00e9 favorable aux strat\u00e9gies de l\u2019industrie du tabac<\/strong><\/h2>\n<p style=\"text-align: justify\">Au-del\u00e0 du d\u00e9bat r\u00e9glementaire, cette \u00e9volution intervient dans un contexte international marqu\u00e9 par l\u2019expansion rapide des nouveaux produits de nicotine et par l\u2019intensification des strat\u00e9gies d\u2019influence de l\u2019industrie du tabac. Plusieurs organisations et acteurs favorables \u00e0 la r\u00e9forme ont soutenu publiquement l\u2019approche argentine au nom de la \u00ab r\u00e9duction des risques \u00bb et de la n\u00e9cessit\u00e9 de \u00ab r\u00e9guler plut\u00f4t qu\u2019interdire \u00bb.<\/p>\n<p style=\"text-align: justify\">Ces arguments reprennent des \u00e9l\u00e9ments r\u00e9guli\u00e8rement mobilis\u00e9s par les fabricants de produits nicotiniques : \u00e9chec de la prohibition, diff\u00e9renciation des risques entre produits ou encore n\u00e9cessit\u00e9 de lutter contre le march\u00e9 informel. Les multinationales du tabac investissent aujourd\u2019hui massivement les segments des cigarettes \u00e9lectroniques, du tabac chauff\u00e9 et des sachets de nicotine afin de maintenir la d\u00e9pendance \u00e0 la nicotine et renouveler leurs march\u00e9s, notamment aupr\u00e8s des jeunes g\u00e9n\u00e9rations.<\/p>\n<p style=\"text-align: justify\">Les sachets de nicotine concern\u00e9s par la r\u00e9forme sont d\u00e9j\u00e0 commercialis\u00e9s par plusieurs grands groupes du tabac sur les march\u00e9s internationaux, notamment British American Tobacco avec VELO ou Philip Morris International avec ZYN. En janvier 2026<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>, plusieurs organismes en sant\u00e9 publique alertaient d\u00e9j\u00e0 sur le d\u00e9veloppement rapide de ces produits en Argentine et sur les strat\u00e9gies de p\u00e9n\u00e9tration du march\u00e9 d\u00e9ploy\u00e9es par l\u2019industrie dans plusieurs pays d\u2019Am\u00e9rique latine.<\/p>\n<p style=\"text-align: justify\">Les acteurs de sant\u00e9 publique soulignent \u00e9galement que le nouveau cadre r\u00e9glementaire ne comporte pratiquement aucune mesure concernant les points de vente, les r\u00e9seaux sociaux ou l\u2019interdiction de tout marketing num\u00e9rique particuli\u00e8rement utilis\u00e9e pour promouvoir ces produits aupr\u00e8s des jeunes publics. Cette absence de contr\u00f4le des pratiques promotionnelles appara\u00eet d\u2019autant plus pr\u00e9occupante que les produits concern\u00e9s reposent largement sur des strat\u00e9gies de s\u00e9duction associant innovation technologique, discr\u00e9tion d\u2019usage, ar\u00f4mes attractifs et forte visibilit\u00e9 num\u00e9rique.<\/p>\n<p style=\"text-align: justify\">Alors que plusieurs pays renforcent actuellement leurs r\u00e9glementations sur les nouveaux produits nicotiniques, notamment par des interdictions d\u2019ar\u00f4mes, des restrictions publicitaires ou des interdictions de certains dispositifs, l\u2019Argentine fait ainsi le choix inverse en revenant sur des interdictions historiques pourtant fond\u00e9es sur des pr\u00e9occupations sanitaires et le principe de pr\u00e9caution.<\/p>\n<p style=\"text-align: justify\"><strong style=\"text-align: justify\"><a href=\"https:\/\/www.generationsanstabac.org\/\">\u00a9G\u00e9n\u00e9ration Sans Tabac<\/a><\/strong><\/p>\n<p style=\"text-align: right\"><em><strong>AE<\/strong><\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Eugenia Leis Montero, <a href=\"https:\/\/chequeado.com\/el-explicador\/pese-a-que-producen-efectos-nocivos-en-la-salud-el-gobierno-habilito-los-vapeadores-y-las-bolsitas-de-nicotina\/\">Pese a que producen efectos nocivos en la salud, el Gobierno habilit\u00f3 los vapeadores y las bolsitas de nicotina<\/a>, Chequeado, publi\u00e9 le 5 mai 2026, consult\u00e9 le 7 mai 2026<\/p>\n<p style=\"text-align: justify\"><a href=\"#_ftnref2\" name=\"_ftn2\"><\/a><a href=\"https:\/\/www.generationsanstabac.org\/fr\/actualites\/sachets-de-nicotine-une-nouvelle-offensive-de-lindustrie-du-tabac-en-argentine\/\"><sup><u>[2]<\/u><\/sup> Sachets de nicotine : une nouvelle offensive de l\u2019industrie du tabac en Argentine<\/a>, G\u00e9n\u00e9ration sans tabac, publi\u00e9 le 13 janvier 2026, consult\u00e9 le 7 mai 2026<\/p>\n<p><strong style=\"color: #999999\"><a style=\"color: #999999\" href=\"http:\/\/www.cnct.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comit\u00e9 national contre le tabagisme |<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Argentine government has adopted a new regulatory framework authorizing the sale of e-cigarettes, heated tobacco products, and nicotine pouches, reversing several years of prohibition on these products in the country. Published in early May 2026, Resolution 549\/2026 establishes an authorization, registration, and control system applicable to new nicotine products. Argentine authorities present this development as a response to the failure of prohibition, arguing that these products continued to circulate widely through informal channels without health or tax controls. <\/p>","protected":false},"featured_media":2944,"template":"","tags":[],"thematique":[516,491],"class_list":["post-26815","actualites","type-actualites","status-publish","has-post-thumbnail","hentry","thematique-nouveaux-produits","thematique-politiques-publiques"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/26815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites"}],"about":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/types\/actualites"}],"version-history":[{"count":1,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/26815\/revisions"}],"predecessor-version":[{"id":26818,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/26815\/revisions\/26818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media\/2944"}],"wp:attachment":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media?parent=26815"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/tags?post=26815"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/thematique?post=26815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}