{"id":26373,"date":"2026-03-09T07:00:44","date_gmt":"2026-03-09T06:00:44","guid":{"rendered":"https:\/\/www.generationsanstabac.org\/?post_type=actualites&#038;p=26373"},"modified":"2026-03-06T11:48:21","modified_gmt":"2026-03-06T10:48:21","slug":"critique-de-linstrumentalisation-du-commerce-illicite-par-lindustrie-du-tabac","status":"publish","type":"actualites","link":"https:\/\/www.generationsanstabac.org\/en\/actualites\/critique-de-linstrumentalisation-du-commerce-illicite-par-lindustrie-du-tabac\/","title":{"rendered":"Critique of the tobacco industry&#039;s exploitation of illicit trade"},"content":{"rendered":"<p style=\"text-align: justify\"><em>Le Centre mondial pour la bonne gouvernance dans la lutte antitabac (GGTC) vient de publier un premier rapport exploitant les donn\u00e9es des indices mondiaux d&rsquo;ing\u00e9rence en mati\u00e8re de politique fiscale sur le tabac (GTI) de 2023 et 2025<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a>. Il ressort que l&rsquo;industrie du tabac utilise le commerce illicite comme argument pour s&rsquo;opposer et faire \u00e9chouer les mesures d&rsquo;augmentation des taxes et de lutte contre le tabagisme dans de nombreux pays. Par ailleurs, au moins 19 pays ont nou\u00e9 des accords avec l\u2019industrie pour lutter contre le commerce illicite. Ce rapport aborde de mani\u00e8re critique les strat\u00e9gies de lobbying de l\u2019industrie bas\u00e9es dans le domaine du commerce illicite et a vocation \u00e0 \u00e9clairer la d\u00e9cision publique de mani\u00e8re factuelle.<\/em><\/p>\n<h2 style=\"text-align: justify\">L&rsquo;industrie du tabac pr\u00e9tend combattre le commerce illicite, sans en apporter la preuve, alors qu\u2019elle l\u2019alimente<\/h2>\n<p style=\"text-align: justify\">Les auteurs du rapport analysent la mani\u00e8re dont le commerce illicite de produits du tabac est utilis\u00e9 dans les discussions sur les politiques publiques. Les entreprises du secteur soutiennent fr\u00e9quemment que certaines mesures de lutte antitabac, en particulier les hausses de taxes et les restrictions marketing pourraient entra\u00eener une augmentation de la contrebande.<\/p>\n<p style=\"text-align: justify\">Selon le document, ces arguments sont souvent mobilis\u00e9s pour contester, ralentir ou affaiblir l\u2019adoption de nouvelles mesures.<\/p>\n<p style=\"text-align: justify\">Le rapport souligne toutefois que ces affirmations doivent \u00eatre examin\u00e9es avec prudence. Plusieurs analyses ind\u00e9pendantes indiquent que les estimations de l\u2019ampleur du commerce illicite produites ou financ\u00e9es par l\u2019industrie du tabac sont surestim\u00e9es, ce qui peut influencer les d\u00e9cisions politiques. Les rapports de KPMG et d&rsquo;Euromonitor International, qui constituent souvent les sources utilis\u00e9es, ont \u00e9t\u00e9 particuli\u00e8rement critiqu\u00e9s pour leur biais de reclassification, leurs faiblesses et leur manque de transparence m\u00e9thodologiques. Ces \u00e9tudes sont financ\u00e9es par les fabricants de tabac et elles comprennent de surcro\u00eet des clauses de non-responsabilit\u00e9 concernant l&rsquo;exactitude des donn\u00e9es.<\/p>\n<p style=\"text-align: justify\">Le rapport rappelle \u00e9galement plusieurs affaires judiciaires et enqu\u00eates internationales mettant en cause des grandes entreprises du tabac. Ces pr\u00e9c\u00e9dents sont pr\u00e9sent\u00e9s comme un \u00e9l\u00e9ment important pour comprendre le d\u00e9bat actuel : ils montrent que l\u2019industrie, tout en affirmant lutter contre la contrebande, a \u00e9t\u00e9 voire demeure impliqu\u00e9e dans des pratiques qui ont contribu\u00e9 au d\u00e9veloppement de march\u00e9s illicites.<\/p>\n<p style=\"text-align: justify\">Dans cette perspective, les auteurs soulignent que les produits de contrebande sortent essentiellement des usines des fabricants. Ainsi, une analyse ind\u00e9pendante de la m\u00e9thodologie de Philip Morris International (PMI) a r\u00e9v\u00e9l\u00e9 que jusqu&rsquo;\u00e0 deux tiers des cigarettes illicites dans le monde sont des produits des principaux fabricants de tabac, qui entrent dans les circuits informels en raison d&rsquo;une offre exc\u00e9dentaire, d&rsquo;un contr\u00f4le insuffisant de la cha\u00eene d&rsquo;approvisionnement et de fuites d\u00e9lib\u00e9r\u00e9es.<\/p>\n<h2 style=\"text-align: justify\">Les risques li\u00e9s aux relations entre gouvernements et industrie dans la lutte contre la contrebande<\/h2>\n<p style=\"text-align: justify\">Le document met \u00e9galement en lumi\u00e8re les formes de collaboration qui peuvent exister entre les autorit\u00e9s publiques et l\u2019industrie du tabac dans la lutte contre le commerce illicite.<\/p>\n<p style=\"text-align: justify\">Ces collaborations prennent diff\u00e9rentes formes : des protocoles d\u2019accord entre gouvernements et entreprises, des programmes de formation ou d\u2019assistance technique aux douanes, du partage d\u2019informations sur les circuits de distribution, ainsi que des op\u00e9rations conjointes de sensibilisation contre la contrebande.<\/p>\n<p style=\"text-align: justify\">Ces accords vont \u00e0 l\u2019encontre des dispositions de la Convention-cadre de l\u2019Organisation mondiale de la sant\u00e9 (OMS) pour la lutte antitabac (CCLAT) qui proscrit tout type d\u2019accord volontaire non contraignant. En outre, ce type d\u2019accord intervient \u00e0 la place de la mise en \u0153uvre de mesures \u00e9prouv\u00e9es pour lutter contre le commerce illicite des produits du tabac. \u00c0 cet \u00e9gard, les auteurs rappellent qu\u2019un Protocole de lutte contre le commerce illicite a \u00e9t\u00e9 \u00e9labor\u00e9 dans le cadre de ce trait\u00e9 de l\u2019OMS, r\u00e9unissant les modalit\u00e9s techniques et judiciaires efficaces. 17 des 19 gouvernements dont il a \u00e9t\u00e9 prouv\u00e9 qu&rsquo;ils collaboraient avec l&rsquo;industrie sur le commerce illicite n&rsquo;\u00e9taient pas parties au Protocole.<\/p>\n<h2 style=\"text-align: justify\">La \u00ab triple perte fiscale \u00bb li\u00e9e \u00e0 ces collaborations<\/h2>\n<p style=\"text-align: justify\">Les auteurs du rapport pointent \u00e9galement les risques li\u00e9s \u00e0 ce type d\u2019accord et ils introduisent le concept de \u00ab triple perte \u00bb : la premi\u00e8re concerne l\u2019aggravation du \u00a0co\u00fbt en sant\u00e9, environnement et social ; la deuxi\u00e8me fait r\u00e9f\u00e9rence aux co\u00fbts li\u00e9s aux op\u00e9rations de lutte contre l\u2019illicite financ\u00e9es par l\u2019\u00c9tat en se basant parfois sur des donn\u00e9es pilot\u00e9es par l\u2019industrie ; la troisi\u00e8me, la perte de recettes fiscales r\u00e9sultant des gels, voire r\u00e9ductions de taxes adopt\u00e9es sous la pression de l\u2019industrie, aggravant le d\u00e9ficit global.<\/p>\n<p style=\"text-align: justify\">Ces pertes fiscales s\u2019inscrivent dans le cadre du co\u00fbt \u00e9conomique mondial du tabac, estim\u00e9 \u00e0 1 400 milliards de dollars (1 200 milliards d\u2019euros) par an, comprenant 422 milliards de dollars (364 millions d\u2019euros) de d\u00e9penses de sant\u00e9, li\u00e9es notamment aux traitements des cancers, maladies cardiovasculaires et maladies respiratoires associ\u00e9es au tabagisme, et environ 980 milliards de dollars (854 milliards d\u2019euros) de pertes de productivit\u00e9, caus\u00e9es par les d\u00e9c\u00e8s pr\u00e9matur\u00e9s, l\u2019absent\u00e9isme et les incapacit\u00e9s li\u00e9es aux maladies.<\/p>\n<p style=\"text-align: justify\">Ces co\u00fbts sont support\u00e9s principalement par les gouvernements, dont 40 % par des pays \u00e0 revenu faible ou interm\u00e9diaire, et les recettes fiscales issues des taxes sur le tabac ne couvrent pas ces d\u00e9penses, entra\u00eenant un d\u00e9ficit fiscal global.<\/p>\n<p style=\"text-align: justify\">Dans les r\u00e9gimes fiscaux sur le tabac tr\u00e8s performants, les recettes provenant des droits d&rsquo;accise ne repr\u00e9sentent qu&rsquo;une fraction, g\u00e9n\u00e9ralement comprise entre 10 et 30 %, de la charge \u00e9conomique totale que le tabac fait peser sur la m\u00eame \u00e9conomie. Le manque \u00e0 gagner cr\u00e9\u00e9 par le commerce illicite est donc une perte dans une situation budg\u00e9taire nette d\u00e9j\u00e0 n\u00e9gative. La r\u00e9duction des taxes pour combler ce d\u00e9ficit ne r\u00e9tablit pas l&rsquo;\u00e9quilibre budg\u00e9taire, elle l&rsquo;aggrave en r\u00e9duisant la compensation partielle tout en laissant les co\u00fbts sanitaires et sociaux sous-jacents totalement inchang\u00e9s.<\/p>\n<h2 style=\"text-align: justify\">Les recommandations du rapport et du Comit\u00e9 national contre le tabagisme (CNCT)<\/h2>\n<p style=\"text-align: justify\">Les auteurs du rapport rappellent les enjeux de prot\u00e9ger les politiques publiques de l\u2019interf\u00e9rence de l\u2019industrie du tabac, en particulier dans ce domaine. Ils pr\u00e9conisent de mettre fin aux accords de coop\u00e9ration existants, de s\u2019appuyer sur des donn\u00e9es ind\u00e9pendantes comme les donn\u00e9es des douanes et les enqu\u00eates sp\u00e9cialis\u00e9es, tout en mettant en \u0153uvre les dispositions du Protocole pr\u00e9voyant un contr\u00f4le de la cha\u00eene d\u2019approvisionnement avec des syst\u00e8mes de suivi et de tra\u00e7abilit\u00e9 des produits ind\u00e9pendants des fabricants, et des m\u00e9canismes de coop\u00e9ration entre pays.<\/p>\n<p style=\"text-align: justify\">Ils rappellent que les dispositions relatives \u00e0 l\u2019article 5.3 de la CCLAT, qui constitue une obligation g\u00e9n\u00e9rale de prot\u00e9ger les politiques publiques, s\u2019appliquent \u00e0 l\u2019ensemble des pouvoirs publics et pas seulement aux autorit\u00e9s sanitaires.<\/p>\n<p style=\"text-align: justify\">Face \u00e0 l\u2019ing\u00e9rence de l\u2019industrie du tabac dans le discours m\u00e9diatique et politique fran\u00e7ais, qui instrumentalise ces questions pour freiner les hausses de taxes, <a href=\"https:\/\/www.generationsanstabac.org\/fr\/actualites\/le-cnct-publie-une-analyse-critique-sur-la-desinformation-autour-des-marches-paralleles-du-tabac\/\">le CNCT lui-m\u00eame pr\u00e9conise une plus grande transparence sur l\u2019origine des amendements et l\u2019adoption de mesures publiques fond\u00e9es sur des donn\u00e9es ind\u00e9pendantes<\/a>. Enfin, <a href=\"https:\/\/www.generationsanstabac.org\/fr\/actualites\/marches-paralleles-le-cnct-demonte-les-arguments-de-lindustrie-du-tabac\/\">dans le cadre de son colloque sur les march\u00e9s parall\u00e8les du tabac<\/a>, le CNCT a appel\u00e9 \u00e0 une limitation des livraisons de produits du tabac dans chaque pays, en les ajustant \u00e0 la pr\u00e9valence du tabagisme et aux niveaux r\u00e9els de consommation, et a exhort\u00e9 la France \u00e0 s\u2019acquitter de ses contributions en tant que Partie au Protocole de l\u2019OMS pour \u00e9liminer le commerce illicite des produits du tabac.<\/p>\n<p style=\"text-align: justify\"><strong style=\"text-align: justify\"><a href=\"https:\/\/www.generationsanstabac.org\/\">\u00a9G\u00e9n\u00e9ration Sans Tabac<\/a><\/strong><\/p>\n<p style=\"text-align: right\"><em><strong>AD<\/strong><\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a>Deborah Sy et Mary Assunta, A Response to Tobacco Industry&rsquo;s Illicit Trade Narratives to Interfere with Policy Making: The Triple Fiscal Loss, Global Center for Good Governance in Tobacco Control (GGTC), publi\u00e9 en mars 2026, consult\u00e9 le 5 mars 2026<\/p>\n<p style=\"text-align: justify\"><strong style=\"color: #999999\"><a style=\"color: #999999\" href=\"http:\/\/www.cnct.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comit\u00e9 national contre le tabagisme |<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Global Governance Centre for Tobacco Control (GGTC) has just published its first report using data from the 2023 and 2025 Global Tobacco Tax Interference Indices (GTI). The report reveals that the tobacco industry is using illicit trade as leverage to oppose and thwart tax increases and tobacco control measures in many countries. Furthermore, at least 19 countries have entered into agreements with the industry to combat illicit trade. This report critically examines the industry&#039;s lobbying strategies based on illicit trade and aims to inform public policy decisions with factual information.<\/p>","protected":false},"featured_media":26376,"template":"","tags":[],"thematique":[538],"class_list":["post-26373","actualites","type-actualites","status-publish","has-post-thumbnail","hentry","thematique-marches-paralleles"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/26373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites"}],"about":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/types\/actualites"}],"version-history":[{"count":2,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/26373\/revisions"}],"predecessor-version":[{"id":26378,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/26373\/revisions\/26378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media\/26376"}],"wp:attachment":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media?parent=26373"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/tags?post=26373"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/thematique?post=26373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}