{"id":21515,"date":"2024-07-01T07:00:57","date_gmt":"2024-07-01T05:00:57","guid":{"rendered":"https:\/\/www.generationsanstabac.org\/actualites\/tabac-chauffe-un-document-interne-revele-loffensive-de-philip-morris-au-japon\/"},"modified":"2024-07-01T07:00:57","modified_gmt":"2024-07-01T05:00:57","slug":"tabac-chauffe-un-document-interne-revele-loffensive-de-philip-morris-au-japon","status":"publish","type":"actualites","link":"https:\/\/www.generationsanstabac.org\/en\/actualites\/tabac-chauffe-un-document-interne-revele-loffensive-de-philip-morris-au-japon\/","title":{"rendered":"Heated tobacco: internal document reveals Philip Morris&#039; offensive in Japan"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Une analyse de plusieurs documents internes de Philip Morris Japan (PMJ) par l\u2019organisme de surveillance STOP<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a> r\u00e9v\u00e8le un vaste plan de commercialisation du dispositif de tabac chauff\u00e9 IQOS qui semble viser \u00e0 attirer une client\u00e8le plus large que celle des fumeurs actuels.<\/em> <em>Le Japon est un march\u00e9 cl\u00e9 pour PMI, puisqu&rsquo;il s&rsquo;agit du march\u00e9 de lancement de l&rsquo;IQOS et que la consommation de produits du tabac chauff\u00e9s y est la plus \u00e9lev\u00e9e au monde.<\/em><\/p>\n<p style=\"text-align: justify;\">\u00ab Aujourd&rsquo;hui le Japon, demain le monde : Philip Morris Japan&rsquo;s Leaked Marketing Blueprint for IQOS \u00bb analyse un document de strat\u00e9gie commerciale interne d&rsquo;avril 2019 de la filiale japonaise de Philip Morris et explique en d\u00e9tail comment PMJ a planifi\u00e9 une strat\u00e9gie sur plusieurs fronts pour influencer les d\u00e9cideurs politiques aux niveaux local, r\u00e9gional, national et m\u00eame international. Le rapport de STOP cite \u00e9galement des preuves que PMI pourrait d\u00e9ployer des tactiques similaires dans d&rsquo;autres pays.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Capter une client\u00e8le allant au de-l\u00e0 des fumeurs actuels<\/strong><\/h2>\n<p style=\"text-align: justify;\">Alors que PMI affirme que l&rsquo;IQOS n&rsquo;est destin\u00e9 qu&rsquo;aux fumeurs adultes, le document sugg\u00e8re que PMJ cherchait \u00e0 atteindre un public beaucoup plus large pour son nouveau produit afin d&rsquo;aider \u00e0 \u00ab acc\u00e9l\u00e9rer l&rsquo;acquisition \u00bb de nouveaux utilisateurs d&rsquo;IQOS. PMJ a fait pression pour que l&rsquo;utilisation de l&rsquo;IQOS soit autoris\u00e9e dans les lieux o\u00f9 il est interdit de fumer et pour que son produit soit tax\u00e9 \u00e0 un taux favorable afin d&rsquo;en garantir l&rsquo;accessibilit\u00e9. Parmi les cibles de ces soutiens figurent des hommes politiques, des groupes m\u00e9dicaux, l&rsquo;agence japonaise de gestion des incendies et des catastrophes, ainsi que des groupes de l&rsquo;h\u00f4tellerie dans une tentative apparente d&rsquo;obtenir une large acceptation de l&rsquo;IQOS dans la soci\u00e9t\u00e9 japonaise. Les documents montrent \u00e9galement que le fabricant souhaitait assurer sa pr\u00e9sence aux Jeux Olympiques de Tokyo de 2020 pour associer son produit au sport et au bien-\u00eatre.<\/p>\n<h2><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter  wp-image-7405\" src=\"https:\/\/www.generationsanstabac.org\/wp-content\/uploads\/2024\/07\/Capturefgfgfgf-1-1024x588.png\" alt=\"\" width=\"1061\" height=\"609\" \/><\/h2>\n<p><img decoding=\"async\" class=\"aligncenter  wp-image-7407\" src=\"https:\/\/www.generationsanstabac.org\/wp-content\/uploads\/2024\/07\/Capturedddd-1-1024x303.png\" alt=\"\" width=\"1048\" height=\"310\" \/><\/p>\n<h2 style=\"text-align: justify;\"><strong>Une strat\u00e9gie de propagande mondiale <\/strong><\/h2>\n<p style=\"text-align: justify;\">L&rsquo;analyse de STOP cite des rapports de presse qui sugg\u00e8rent que PMI pourrait tenter de cultiver une influence similaire dans d&rsquo;autres pays, \u00e0 travers des contacts avec des ministres du gouvernement et des conseils locaux au Royaume-Uni, un r\u00e9seau national de lobbyistes aux \u00c9tats-Unis. Sont \u00e9galement \u00e9voqu\u00e9s des projets de vente du dispositif de tabac chauff\u00e9 IQOS dans des pubs, des bars et des clubs en Australie, le ciblage de l&rsquo;industrie du tourisme et de l&rsquo;h\u00f4tellerie en Gr\u00e8ce, R\u00e9publique tch\u00e8que ou encore aux Canaries, et des tentatives de recrutement de dentistes comme d\u00e9fenseurs de l&rsquo;IQOS en Allemagne.<\/p>\n<p style=\"text-align: justify;\">En France, Philip Morris a massivement investi les bureaux de tabac pour y faire la promotion de son tabac chauff\u00e9 et utilise la Conf\u00e9d\u00e9ration des buralistes comme porte-voix pour porter des amendements favorables au tabac chauff\u00e9. Le cigarettier poss\u00e8de plusieurs sites web faisant la promotion indirecte de ce produit qu\u2019il pr\u00e9sente comme \u00ab moins nocif \u00bb, malgr\u00e9 l&rsquo;absence de preuves scientifiques sur l&rsquo;impact \u00e0 long terme du produit sur la sant\u00e9. Le cigarettier tente \u00e9galement de participer \u00e0 des \u00e9v\u00e9nements parrain\u00e9s par les minist\u00e8res \u00e0 l\u2019instar du Salon Produrable ou des Dialogues de l\u2019inclusion et de la RSE pour \u00e9changer sur ses perspectives commerciales et faire la promotion de ses \u00ab produits sans combustion \u00bb. Cependant, suite aux alertes donn\u00e9es par le Comit\u00e9 national contre le tabagisme (CNCT) et \u00e0 la mobilisation de la soci\u00e9t\u00e9 civile en France et \u00e0 l\u2019international, la participation du fabricant aux Dialogues de l\u2019Inclusion et de la RSE a finalement \u00e9t\u00e9 annul\u00e9e et suite aux d\u00e9marches effectu\u00e9es aupr\u00e8s du Minist\u00e8re de la transition \u00e9cologique par le CNCT, la participation de Philip Morris au salon Pro durable a \u00e9t\u00e9 annul\u00e9e en 2023.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un investissement massif dans le monde scientifique et m\u00e9dical <\/strong><\/h2>\n<p style=\"text-align: justify;\">Des chercheurs du Tobacco Control Research Group de l&rsquo;universit\u00e9 de Bath<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> ont analys\u00e9 d\u2019autres documents de PMJ qui montrent que le fabricant a secr\u00e8tement financ\u00e9, par l&rsquo;interm\u00e9diaire d&rsquo;un tiers (la CCIM &#8211; La plus grande organisation de recherche sous contrat du Japon qui offre un soutien au d\u00e9veloppement de produits pharmaceutiques), une \u00e9tude sur le sevrage tabagique au Japon r\u00e9alis\u00e9e par des universitaires, qui ont depuis \u00ab n\u00e9glig\u00e9 \u00bb de d\u00e9clarer leur relation avec PMJ dans une publication ult\u00e9rieure.<\/p>\n<p style=\"text-align: justify;\">PMJ a tout particuli\u00e8rement souhait\u00e9 avoir acc\u00e8s \u00e0 la communaut\u00e9 dentaire japonaise et obtenir son soutien car en 2019, PMI menait un essai clinique au Japon pour \u00e9tudier les effets d&rsquo;IQOS sur la sant\u00e9 bucco-dentaire et le traitement de la parodontite.<\/p>\n<p style=\"text-align: justify;\">Pour mener \u00e0 bien sa strat\u00e9gie, PMJ a \u00e9galement engag\u00e9 une soci\u00e9t\u00e9 japonaise de conseil en sciences de la vie (FTI-I) \u00e0 hauteur de 3 000 000 \u00a5 (environ 17 500\u20ac) par mois entre 2014 et 2019 pour lui faciliter l\u2019acc\u00e8s \u00e0 des leaders d&rsquo;opinion et \u00e0 des \u00e9v\u00e9nements cl\u00e9s qui lui ont permis de promouvoir la rh\u00e9torique de la \u00ab r\u00e9duction des risques \u00bb.  FTI-I a ainsi fourni \u00e0 PMJ une liste d\u2019universit\u00e9s qui autorisaient la participation de l\u2019industrie du tabac \u00e0 leurs conf\u00e9rences. FTI-I a \u00e9galement conseill\u00e9 et soutenu la recherche scientifique de PMJ, y compris le \u00ab soutien pratique pour le mod\u00e8le m\u00e9dico-\u00e9conomique \u00bb, \u00ab des conseils sur le protocole d&rsquo;essai, l&rsquo;\u00e9thique et les conflits d&rsquo;int\u00e9r\u00eats \u00bb, \u00ab le soutien \u00e0 des discussions avec des chercheurs \u00e9trangers \u00bb. Outre la communaut\u00e9 m\u00e9dicale notamment celle des dentistes, FTI-I a cherch\u00e9 \u00e0 \u00e9tablir des relations avec d&rsquo;autres secteurs, tels que les assurances, les industries pharmaceutiques.<\/p>\n<p><strong><a href=\"https:\/\/www.generationsanstabac.org\/\">\u00a9G\u00e9n\u00e9ration Sans Tabac<\/a><\/strong><\/p>\n<p style=\"text-align: right;\"><em><strong>AE<\/strong><\/em><\/p>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Rapport, Today Japan, <a href=\"https:\/\/exposetobacco.org\/wp-content\/uploads\/PMJ-leaked-marketing-blueprint_EN.pdf\">Tomorrow the World Philip Morris Japan\u2019s Leaked Marketing Blueprint for IQOS<\/a>, STOP, juin 2024<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Sophie Braznell, Louis Laurence, Iona Fitzpatrick, Anna B Gilmore, \u201c<em>Keep it a secret<\/em>\u201d: leaked documents suggest Philip Morris International, and its Japanese affiliate, continue to exploit science for profit, <em>Nicotine &amp; Tobacco Research<\/em>, 2024;, ntae101, <a href=\"https:\/\/doi.org\/10.1093\/ntr\/ntae101\">https:\/\/doi.org\/10.1093\/ntr\/ntae101<\/a><\/p>\n<p><span style=\"color: #999999;\"><strong><a style=\"color: #999999;\" href=\"http:\/\/www.cnct.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comit\u00e9 national contre le tabagisme |<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>An analysis of several internal Philip Morris Japan (PMJ) documents by the watchdog STOP reveals a broad marketing plan for the IQOS heated tobacco device that appears to be aimed at attracting a broader customer base beyond current smokers. Japan is a key market for PMI, as it was the launch market for IQOS and has the highest consumption of heated tobacco products in the world.<\/p>","protected":false},"featured_media":19660,"template":"","tags":[],"thematique":[499,474],"class_list":["post-21515","actualites","type-actualites","status-publish","has-post-thumbnail","hentry","thematique-lobby","thematique-sante"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/21515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites"}],"about":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/types\/actualites"}],"version-history":[{"count":0,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/21515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media\/19660"}],"wp:attachment":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media?parent=21515"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/tags?post=21515"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/thematique?post=21515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}