{"id":21456,"date":"2024-05-17T07:00:52","date_gmt":"2024-05-17T05:00:52","guid":{"rendered":"https:\/\/www.generationsanstabac.org\/actualites\/philip-morris-egypte-partenariat-conteste-united-tobacco\/"},"modified":"2024-05-17T07:00:52","modified_gmt":"2024-05-17T05:00:52","slug":"philip-morris-egypte-partenariat-conteste-united-tobacco","status":"publish","type":"actualites","link":"https:\/\/www.generationsanstabac.org\/en\/actualites\/philip-morris-egypte-partenariat-conteste-united-tobacco\/","title":{"rendered":"Philip Morris enters Egyptian market after disputed tender"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Philip Morris International (PMI) a pris une participation dans la soci\u00e9t\u00e9 \u00ab United Tobacco \u00bb qui a r\u00e9cemment obtenu une licence pour fabriquer et commercialiser des cigarettes en \u00c9gypte, l&rsquo;un des march\u00e9s du tabac les plus convoit\u00e9s au monde. L\u2019actionnariat complet d&rsquo;United Tobacco n\u2019a pas \u00e9t\u00e9 divulgu\u00e9 et le processus d&rsquo;octroi de licences a \u00e9t\u00e9 contest\u00e9 par les entreprises concurrentes.<\/em><\/p>\n<p style=\"text-align: justify;\">Les m\u00e9dias The Examination<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> et l&rsquo;Organized Crime and Corruption Reporting Project (OCCRP)<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> ont analys\u00e9 des centaines de documents provenant de registres d&rsquo;entreprises, de d\u00e9p\u00f4ts de titres et de documents juridiques du Moyen-Orient, d&rsquo;Europe et des \u00c9tats-Unis. Ils ont \u00e9galement interrog\u00e9 des fonctionnaires \u00e9gyptiens actuellement en poste ou qui l\u2019ont \u00e9t\u00e9 dans le pass\u00e9, des employ\u00e9s de l&rsquo;industrie du tabac, des responsables de la sant\u00e9 publique et des experts \u00e9conomiques afin de comprendre les relations entre le cigarettier et United Tobacco.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7231\" src=\"https:\/\/www.generationsanstabac.org\/wp-content\/uploads\/2024\/07\/the-examination-philip-morris-egypt-909x1024.jpg\" alt=\"the-examination-philip-morris-egypt\" width=\"753\" height=\"848\" \/><\/p>\n<p style=\"text-align: center;\"><em>Figure 1 &#8211; Source : The Examination<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong> <\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\"><strong>Des interrogations sur la propri\u00e9t\u00e9 d\u2019United Tobacco<\/strong><\/h2>\n<p style=\"text-align: justify;\">Les efforts d\u00e9ploy\u00e9s par Philip Morris et d\u2019autres fabricants de tabac pour dominer le march\u00e9 \u00e9gyptien ont longtemps \u00e9t\u00e9 frein\u00e9s par l&rsquo;Eastern Company d&rsquo;\u00c9gypte, qui contr\u00f4lait jusqu&rsquo;\u00e0 r\u00e9cemment l&rsquo;ensemble de la production de cigarettes dans ce pays et \u00e9tait d\u00e9tenue majoritairement par l&rsquo;\u00c9tat. Toutefois, sous la pression du Fonds mon\u00e9taire international qui demande au gouvernement de privatiser les actifs de l&rsquo;\u00c9tat pour b\u00e9n\u00e9ficier d\u2019aides et de pr\u00eats, l&rsquo;\u00c9gypte a rel\u00e2ch\u00e9 son emprise sur l&rsquo;industrie du tabac, permettant ainsi aux investisseurs priv\u00e9s d\u2019entrer dans ce secteur.<\/p>\n<p style=\"text-align: justify;\">En 2021, l&rsquo;Autorit\u00e9 \u00e9gyptienne de d\u00e9veloppement industriel a donc invit\u00e9 les fabricants de tabac priv\u00e9s \u00e0 soumettre une offre en vue d&rsquo;une licence de fabrication de cigarettes. En avril 2022, l&rsquo;appel d&rsquo;offres a \u00e9t\u00e9 attribu\u00e9 \u00e0 United Tobacco Company. \u00c0 l&rsquo;\u00e9poque, les m\u00e9dias ont d\u00e9crit United Tobacco comme une \u00ab filiale \u00bb de PMI, mais la participation de l&rsquo;entreprise suisse n&rsquo;a \u00e9t\u00e9 confirm\u00e9e dans un document d\u00e9pos\u00e9 aupr\u00e8s de la Securities and Exchange Commission (Commission des valeurs mobili\u00e8res des \u00c9tats-Unis) qu\u2019\u00e0 la mi-2023.<\/p>\n<p style=\"text-align: justify;\">PMI d\u00e9tient des parts dans United Tobacco aux c\u00f4t\u00e9s de l&rsquo;homme d&rsquo;affaires \u00e9mirati Abdullah Al Hussaini, qui distribue des cigarettes pour PMI depuis des d\u00e9cennies, et de Eastern Company, qui a acquis 24 % de United Tobacco lors de l&rsquo;attribution de la licence. Ensemble, PMI, Eastern et une soci\u00e9t\u00e9 britannique d\u00e9tenue en partie par Al Hussaini contr\u00f4lent environ 62 % de United Tobacco, mais l&rsquo;identit\u00e9 des autres actionnaires n\u2019a pas \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Shana Marshall, directrice associ\u00e9e de l&rsquo;Institut d&rsquo;\u00e9tudes sur le Moyen-Orient \u00e0 l&rsquo;universit\u00e9 George Washington, a d\u00e9clar\u00e9 \u00e0 The Examination que l&rsquo;absence de communication des actionnaires des entreprises en \u00c9gypte pourrait indiquer l&rsquo;implication d&rsquo;entreprises appartenant \u00e0 l&rsquo;arm\u00e9e \u00e9gyptienne, question sensible au niveau national. L&rsquo;arm\u00e9e conserve parfois des participations minoritaires dans des industries strat\u00e9giques sur le plan politique ou \u00e9conomique. L\u2019arm\u00e9e est \u00e9galement partie prenante dans le cadre de \u00ab concessions sp\u00e9ciales que les actionnaires d\u2019entreprises doivent accepter pour op\u00e9rer en \u00c9gypte \u00bb, a d\u00e9clar\u00e9 Mme Marshall, qui a pr\u00e9cis\u00e9 qu&rsquo;elle ne savait pas si l&rsquo;arm\u00e9e \u00e9tait impliqu\u00e9e dans l&rsquo;affaire United Tobacco.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un contrat contest\u00e9 par les concurrents de Philip Morris<\/strong><\/h2>\n<p style=\"text-align: justify;\">Selon The Examination, il s&rsquo;agissait en th\u00e9orie d&rsquo;un appel d&rsquo;offres ouvert. Mais dans la pratique, les r\u00e8gles ont favoris\u00e9 Philip Morris International. Les crit\u00e8res de l\u2019appel d&rsquo;offres pr\u00e9cisaient que le nouveau titulaire devra produire au moins 15 milliards de cigarettes par an en \u00c9gypte pour obtenir la licence. Seule une soci\u00e9t\u00e9 internationale, Philip Morris International, vendait alors ce nombre de cigarettes par an dans le pays. Les repr\u00e9sentants de British American Tobacco, Japan Tobacco et Imperial Group &#8211; dont les ventes combin\u00e9es sont inf\u00e9rieures au quota de 15 milliards &#8211; ont protest\u00e9 dans des lettres conjointes adress\u00e9es au premier ministre \u00e9gyptien Mostafa Madbouly.<\/p>\n<p style=\"text-align: justify;\">Les conditions ont \u00e9t\u00e9 modifi\u00e9es, ramenant le quota \u00e0 1 milliard de cigarettes, mais les entreprises ont toujours refus\u00e9 de participer, se plaignant \u00e0 M. Madbouly que l&rsquo;octroi d&rsquo;une seule licence entra\u00eenerait une \u00ab distorsion du march\u00e9 \u00bb et de \u00ab nouvelles formes de monopole \u00bb. PMI est le seul des quatre principaux acteurs du secteur du tabac en \u00c9gypte \u00e0 ne pas avoir sign\u00e9 la lettre de protestation contre le processus d&rsquo;octroi de licences, et United Tobacco a \u00e9t\u00e9 le seul soumissionnaire lors de la phase finale.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Al Hussaini et Philip Morris point\u00e9s comme les acteurs cl\u00e9s du commerce illicite de tabac dans la r\u00e9gion<\/strong><\/h2>\n<p style=\"text-align: justify;\">Dans un proc\u00e8s intent\u00e9 en 2020 \u00e0 New York, un autre partenaire commercial de Philip Morris International, Raoul Setrouk, a affirm\u00e9 que, dans les ann\u00e9es 1990, une soci\u00e9t\u00e9 \u00e9troitement li\u00e9e \u00e0 Al Hussaini avait collabor\u00e9 avec Philip Morris pour faire passer des cigarettes de contrebande dans la r\u00e9gion et contourner les sanctions impos\u00e9es par les \u00c9tats-Unis \u00e0 la Libye.<\/p>\n<p style=\"text-align: justify;\">Setrouk a \u00e9galement affirm\u00e9 qu&rsquo;Al Rashideen distribue des cigarettes pour Philip Morris International en \u00ab Alg\u00e9rie, en \u00c9gypte, en Jordanie, dans les \u00c9tats du Golfe et dans toute l&rsquo;Afrique \u00bb et que \u00ab la plupart des produits de contrebande trouv\u00e9s dans les pays europ\u00e9ens ou dans les zones de conflit proviennent du partenariat tr\u00e8s \u00e9troit entre Al Rashideen et Philip Morris International \u00bb. D&rsquo;anciens documents de PMI, rendus publics en 1998 \u00e0 la suite d&rsquo;une s\u00e9rie de proc\u00e8s historiques intent\u00e9s par les \u00c9tats-Unis contre les quatre plus grands fabricants de tabac du monde, montrent qu&rsquo;Al Hussaini a commenc\u00e9 \u00e0 distribuer les cigarettes de Philip Morris International en Iran en 1991, juste au moment o\u00f9 la R\u00e9publique islamique commen\u00e7ait \u00e0 normaliser ses relations commerciales avec les \u00c9tats-Unis. En 1995, apr\u00e8s que le pr\u00e9sident Bill Clinton a impos\u00e9 de nouvelles sanctions \u00e0 l&rsquo;Iran, Al Hussaini et un cadre du g\u00e9ant du tabac bas\u00e9 en Suisse ont \u00e9chang\u00e9 des lettres pour discuter de la mani\u00e8re de contourner les nouvelles restrictions.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un contrat qui va \u00e0 l\u2019encontre du \u00ab monde sans fum\u00e9e \u00bb affich\u00e9 par Philip Morris<\/strong><\/h2>\n<p style=\"text-align: justify;\">Ces accords, conclus sans grande publicit\u00e9, interviennent alors que Philip Morris International s&rsquo;est officiellement engag\u00e9 \u00e0 parvenir \u00e0 un \u00ab monde sans fum\u00e9e \u00bb et \u00e0 diminuer ses ventes de cigarettes manufactur\u00e9es au profit de nouveaux produits \u00e0 base de nicotine.  En 2017, PMI a officiellement pr\u00e9sent\u00e9 sa vision d&rsquo;un avenir \u00ab sans fum\u00e9e \u00bb. Andr\u00e9 Calantzopoulos, l&rsquo;ancien directeur g\u00e9n\u00e9ral, a alors commenc\u00e9 \u00e0 donner des interviews sur la \u00ab transformation \u00bb de son entreprise. Il voulait faire passer les fumeurs \u00e0 la nouvelle gamme de substituts de cigarettes de PMI, qui, selon lui, am\u00e9liorerait la sant\u00e9 publique.<\/p>\n<p style=\"text-align: justify;\">En r\u00e9alit\u00e9, la mission d\u2019un monde \u00ab sans fum\u00e9e \u00bb est une vaste campagne marketing pour le dispositif de tabac chauff\u00e9 IQOS de PMI et une tentative de r\u00e9habiliter l&rsquo;image de l&rsquo;entreprise afin qu&rsquo;elle puisse \u00e0 nouveau chercher \u00e0 influencer les politiques et les r\u00e9glementations. Le cigarettier d\u00e9ploie activement sa campagne pour le tabac chauff\u00e9 dans les pays o\u00f9 les taux de tabagisme ont baiss\u00e9 ces derni\u00e8res ann\u00e9es mais continue en parall\u00e8le \u00e0 promouvoir activement ses cigarettes manufactur\u00e9es dans de nombreux pays en d\u00e9veloppement et \u00e0 s\u2019opposer aux mesures visant \u00e0 r\u00e9duire le tabagisme. Les exp\u00e9ditions de cigarettes ont ainsi augment\u00e9 de pr\u00e8s de 5% au Moyen-Orient et en Afrique, d&rsquo;environ 2% dans les Am\u00e9riques et de 1,5% en Asie du Sud et du Sud-Est<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Avec 114 milliards de cigarettes vendues en 2022, l\u2019Egypte reste l&rsquo;un des rares pays o\u00f9 la demande de tabac devrait augmenter, ce qui en fait un march\u00e9 tr\u00e8s convoit\u00e9 et lucratif pour le cigarettier.<\/p>\n<hr \/>\n<p style=\"text-align: left;\"><strong><a href=\"https:\/\/www.generationsanstabac.org\/\">\u00a9G\u00e9n\u00e9ration Sans Tabac<\/a><\/strong><\/p>\n<p style=\"text-align: right;\"><b><i>AE<\/i><\/b><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Jason McLure, Aisha Kehoe Down, Lara Dihmis, <a href=\"https:\/\/www.theexamination.org\/articles\/how-philip-morris-international-secured-a-stake-in-one-of-the-world-s-few-growing-cigarette-markets\">How Philip Morris International secured a stake in one of the world\u2019s few growing cigarette markets<\/a>, The Examination, publi\u00e9 le 8 mai 2024, consult\u00e9 le 13 mai 2024<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Jason McLure, Aisha Kehoe Down, Lara Dihmis, <a href=\"https:\/\/www.occrp.org\/en\/investigations\/philip-morris-enters-egypt-market-following-disputed-tender\">Philip Morris Enters Egypt Market Following Disputed Tender<\/a>, OCCRP, publi\u00e9 le 8 mai 2024, consult\u00e9 le 13 mai 2024<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> <a href=\"https:\/\/exposetobacco.org\/news\/pmi-smoke-free-future\/\">Is PMI Really Creating a \u2018Smoke-Free Future\u2019<\/a>?, STOP, publi\u00e9 le 10 avril 2023, consult\u00e9 le 13 mai 2024<\/p>\n<p><span style=\"color: #999999;\"><strong><a style=\"color: #999999;\" href=\"http:\/\/www.cnct.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comit\u00e9 national contre le tabagisme |<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Philip Morris International (PMI) has acquired a stake in United Tobacco, which recently obtained a license to manufacture and market cigarettes in Egypt, one of the world&#039;s most sought-after tobacco markets. United Tobacco&#039;s full ownership has not been disclosed, and the licensing process has been contested by competing companies.<\/p>","protected":false},"featured_media":21458,"template":"","tags":[],"thematique":[499,538],"class_list":["post-21456","actualites","type-actualites","status-publish","has-post-thumbnail","hentry","thematique-lobby","thematique-marches-paralleles"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/21456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites"}],"about":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/types\/actualites"}],"version-history":[{"count":0,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/21456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media\/21458"}],"wp:attachment":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media?parent=21456"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/tags?post=21456"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/thematique?post=21456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}