{"id":19651,"date":"2020-04-08T07:26:06","date_gmt":"2020-04-08T05:26:06","guid":{"rendered":"https:\/\/www.generationsanstabac.org\/actualites\/collusion-du-cigarettier-philip-morris-avec-des-agents-des-douanes-en-italie\/"},"modified":"2020-04-08T07:26:06","modified_gmt":"2020-04-08T05:26:06","slug":"collusion-du-cigarettier-philip-morris-avec-des-agents-des-douanes-en-italie","status":"publish","type":"actualites","link":"https:\/\/www.generationsanstabac.org\/en\/actualites\/collusion-du-cigarettier-philip-morris-avec-des-agents-des-douanes-en-italie\/","title":{"rendered":"Philip Morris Cigarette Collusion with Italian Customs Agents"},"content":{"rendered":"<p>Une enqu\u00eate de l\u2019OCCRP, <em>Organized crime and corruption reporting project<\/em>, a r\u00e9cemment r\u00e9v\u00e9l\u00e9 l\u2019arrestation de plusieurs responsables des douanes en Italie corrompus par le cigarettier Philip Morris<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>Ce dernier par l\u2019entremise d\u2019un de ses responsables Leo Checcaglini, a ainsi pu b\u00e9n\u00e9ficier d\u2019informations confidentielles et de conditions avantageuses par rapport \u00e0 ses concurrents, en particulier dans la fixation des prix, le retard de la mise en \u0153uvre de mesures.<\/p>\n<p>Au-del\u00e0 de cette situation susceptible de lui permettre de mieux dominer le march\u00e9 l\u00e9gal italien, les d\u00e9marches de corruption du cigarettier ont plus particuli\u00e8rement concern\u00e9 les dispositifs de suivi et de tra\u00e7abilit\u00e9 cens\u00e9s permettre aux les autorit\u00e9s publiques de lutter contre le commerce illicite des produits du tabac. Un tel contr\u00f4le n\u2019a jamais \u00e9t\u00e9 du go\u00fbt des cigarettiers, impliqu\u00e9s \u00e0 de nombreuses reprises dans l\u2019organisation m\u00eame des trafics.<\/p>\n<p>Aussi, \u00e0 travers des soci\u00e9t\u00e9s qui s\u2019affirment ind\u00e9pendantes du fabricant et qui, en r\u00e9alit\u00e9, sont \u00e9troitement li\u00e9es \u00e0 son activit\u00e9, le cigarettier a \u00e9t\u00e9 ais\u00e9ment en mesure de mettre \u00e0 mal les garanties affich\u00e9es par le dispositif actuel europ\u00e9en. Le tiers utilis\u00e9 par Philip Morris est ici la soci\u00e9t\u00e9 Fata Logistic Systems. Ce dernier d\u00e9veloppe des logiciels. Il a notamment travaill\u00e9 pour celui du cigarettier et des autres fabricants de tabac Codentify, ses locaux sont situ\u00e9s au sein m\u00eame des b\u00e2timents de Philip Morris pr\u00e8s de Bologne. La soci\u00e9t\u00e9 semble bien continuer \u00e0 fournir un soutien logistique au cigarettier. Pourtant, elle a \u00e9t\u00e9 agr\u00e9\u00e9e par les douanes pour assurer une mission de contr\u00f4le de celui-ci dans le nouveau syst\u00e8me mis en place.<\/p>\n<p>Les investigations de l\u2019OCCRP remettent donc clairement en question l\u2019ind\u00e9pendance globale du syst\u00e8me europ\u00e9en en Italie et sa fiabilit\u00e9.<\/p>\n<p><span style=\"color: #666699;\"><a style=\"color: #666699;\" href=\"https:\/\/www.generationsanstabac.org\/\">\u00a9G\u00e9n\u00e9ration Sans Tabac<\/a><\/span><\/p>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Organized crime and corruption reporting project. <a href=\"https:\/\/www.occrp.org\/en\/loosetobacco\/without-a-trace\/tobaccopoli-the-secret-battle-to-control-italys-cigarette-market\">https:\/\/www.occrp.org\/en\/loosetobacco\/without-a-trace\/tobaccopoli-the-secret-battle-to-control-italys-cigarette-market<\/a><\/p>\n<p><span style=\"color: #e8e8e8;\"><strong><a style=\"color: #e8e8e8;\" href=\"http:\/\/www.cnct.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\"> \u00a9Comit\u00e9 National Contre le Tabagisme |<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>An OCCRP investigation recently revealed the arrest of several Italian customs officials bribed by cigarette maker Philip Morris.<\/p>","protected":false},"featured_media":11348,"template":"","tags":[],"thematique":[499,538],"class_list":["post-19651","actualites","type-actualites","status-publish","has-post-thumbnail","hentry","thematique-lobby","thematique-marches-paralleles"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/19651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites"}],"about":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/types\/actualites"}],"version-history":[{"count":0,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/actualites\/19651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media\/11348"}],"wp:attachment":[{"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/media?parent=19651"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/tags?post=19651"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.generationsanstabac.org\/en\/wp-json\/wp\/v2\/thematique?post=19651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}